{"id":1726,"date":"2023-10-25T10:04:03","date_gmt":"2023-10-25T08:04:03","guid":{"rendered":"https:\/\/softproof.com\/?page_id=1726"},"modified":"2025-05-31T00:23:16","modified_gmt":"2025-05-30T22:23:16","slug":"renderizado-de-colores-planos","status":"publish","type":"page","link":"https:\/\/softproof.com\/es\/spotcolor-rendering\/","title":{"rendered":"Renderizado Spotcolor"},"content":{"rendered":"<div class=\"gb-container gb-container-2115e584\">\n\n<p class=\"wp-block-paragraph\">Utilizar colores planos en SpectraProof es f\u00e1cil: Puede utilizar cualquier archivo CxF o CGATS para importar los datos espectrales medidos en SpectraProof y obtener una visualizaci\u00f3n precisa de los colores planos. O puede utilizar la herramienta de medici\u00f3n incorporada y medir directamente los datos espectrales en modo M0\/M1\/M2 en SpectraProof. Todos los Spotcolor espectrales medidos o importados pueden nombrarse y clasificarse en bibliotecas de color individuales. \u00c9stas pueden utilizarse despu\u00e9s en SpectraProof a escala de cliente, proyecto, impresora, tinta o sustrato, por ejemplo.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"407\" height=\"644\" src=\"https:\/\/softproof.com\/wp-content\/uploads\/2023\/11\/SpectraProof_spotcolor_rendering.png\" alt=\"Soluci\u00f3n Spectraproof Softproof: Men\u00fa de renderizado con Softproof Condici\u00f3n de salida, simulaci\u00f3n de papel, colores planos y mucho m\u00e1s\" class=\"wp-image-1945\" srcset=\"https:\/\/softproof.com\/wp-content\/uploads\/2023\/11\/SpectraProof_spotcolor_rendering.png 407w, https:\/\/softproof.com\/wp-content\/uploads\/2023\/11\/SpectraProof_spotcolor_rendering-300x475.png 300w, https:\/\/softproof.com\/wp-content\/uploads\/2023\/11\/SpectraProof_spotcolor_rendering-190x300.png 190w, https:\/\/softproof.com\/wp-content\/uploads\/2023\/11\/SpectraProof_spotcolor_rendering-8x12.png 8w\" sizes=\"(max-width: 407px) 100vw, 407px\" \/><\/figure>\n<\/div>\n<\/div>\n\n<div class=\"gb-container gb-container-3594ddf4\">\n<div class=\"gb-container gb-container-6d70f80f\">\n\n<p class=\"wp-block-paragraph\">Incluso pueden importarse rampas para todos los colores planos en formato CxF o CGATS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">CGS CXF Color Cloud es actualmente compatible con SpectraProof. Esto permite gestionar o integrar las bases de datos de color CGS existentes.<br>Todo lo que el usuario puede hacer con la caja de herramientas CxF de CGS se almacena como resultado en CGS Color Cloud. Tambi\u00e9n se puede sincronizar con SpectraProof.<br>El motor de predicci\u00f3n espectral de SpectraProof funciona de forma \u00f3ptima si existen rampas de color CxF-4 que hayan sido impresas contra negro y contra papel, idealmente incluso contra gris. Si los datos CxF-4 contienen estas rampas, SpectraProof puede simular la mejor sobreimpresi\u00f3n y mezcla de colores planos, ya que se conoce la informaci\u00f3n de opacidad de los colores planos.Si no se incluyen rampas, SpectraProof trabaja bas\u00e1ndose en el perfil ICC con una previsi\u00f3n de c\u00f3mo se comportar\u00e1 este color plano en este proceso de impresi\u00f3n. A continuaci\u00f3n, SpectraProof sintetiza las rampas de color. De este modo, cada color directo puede reproducirse tanto por s\u00ed solo como en combinaci\u00f3n con otros colores directos, as\u00ed como en combinaci\u00f3n con colores de proceso mediante una distribuci\u00f3n espectral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cada p\u00edxel se calcula espectralmente para su visualizaci\u00f3n en la pantalla. SpectraProof consigue una visualizaci\u00f3n mejor y m\u00e1s precisa de lo que es posible con Photoshop u otras soluciones de prueba suave.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img decoding=\"async\" width=\"651\" height=\"470\" src=\"https:\/\/softproof.com\/wp-content\/uploads\/2025\/05\/MeasuringColors.png\" alt=\"En Spectraproof, puede utilizar espectrofot\u00f3metros como el X-Rite i1Pro2 o el KonicaMinolta MYIRO-1 para medir espectralmente los colores en M0\/M1\/M2 y almacenar las mediciones para suavizar los colores.\" class=\"wp-image-3372\" srcset=\"https:\/\/softproof.com\/wp-content\/uploads\/2025\/05\/MeasuringColors.png 651w, https:\/\/softproof.com\/wp-content\/uploads\/2025\/05\/MeasuringColors-300x217.png 300w, https:\/\/softproof.com\/wp-content\/uploads\/2025\/05\/MeasuringColors-18x12.png 18w, https:\/\/softproof.com\/wp-content\/uploads\/2025\/05\/MeasuringColors-600x433.png 600w\" sizes=\"(max-width: 651px) 100vw, 651px\" \/><figcaption class=\"wp-element-caption\">En Spectraproof, puede utilizar espectrofot\u00f3metros como el X-Rite i1Pro2 o el KonicaMinolta MYIRO-1 para medir espectralmente los colores en M0\/M1\/M2 y almacenar las mediciones para suavizar los colores.<\/figcaption><\/figure>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Utilizar colores planos en SpectraProof es f\u00e1cil: Puede utilizar cualquier archivo CxF o CGATS para importar los datos espectrales medidos en SpectraProof y obtener una visualizaci\u00f3n precisa de los colores planos. O puede utilizar la herramienta de medici\u00f3n incorporada y medir directamente los datos espectrales en modo M0\/M1\/M2 en SpectraProof. Todos los Spotcolor espectrales medidos o importados pueden nombrarse y ordenarse en ... <a title=\"Renderizado Spotcolor\" class=\"read-more\" href=\"https:\/\/softproof.com\/es\/spotcolor-rendering\/\" aria-label=\"Leer m\u00e1s sobre Spotcolor Rendering\">Leer m\u00e1s<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"CBBTypography":[],"footnotes":""},"class_list":["post-1726","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spotcolor Rendering - Softproof.com<\/title>\n<meta name=\"description\" content=\"SpectraProof allows you to import measured spectral data from any CxF or CGATS files to display spotcolor .\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/softproof.com\/es\/renderizado-de-colores-planos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spotcolor Rendering - Softproof.com\" \/>\n<meta property=\"og:description\" content=\"SpectraProof allows you to import measured spectral data from any CxF or CGATS files to display spotcolor .\" \/>\n<meta property=\"og:url\" content=\"https:\/\/softproof.com\/es\/renderizado-de-colores-planos\/\" \/>\n<meta property=\"og:site_name\" content=\"Softproof.com\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-30T22:23:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/softproof.com\/wp-content\/uploads\/2023\/11\/SpectraProof_spotcolor_rendering.png\" \/>\n\t<meta property=\"og:image:width\" content=\"407\" \/>\n\t<meta property=\"og:image:height\" content=\"644\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/softproof.com\\\/spotcolor-rendering\\\/\",\"url\":\"https:\\\/\\\/softproof.com\\\/spotcolor-rendering\\\/\",\"name\":\"Spotcolor Rendering - Softproof.com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/softproof.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/softproof.com\\\/spotcolor-rendering\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/softproof.com\\\/spotcolor-rendering\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/softproof.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/SpectraProof_spotcolor_rendering.png\",\"datePublished\":\"2023-10-25T08:04:03+00:00\",\"dateModified\":\"2025-05-30T22:23:16+00:00\",\"description\":\"SpectraProof allows you to import measured spectral data from any CxF or CGATS files to display spotcolor .\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/softproof.com\\\/spotcolor-rendering\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/softproof.com\\\/spotcolor-rendering\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/softproof.com\\\/spotcolor-rendering\\\/#primaryimage\",\"url\":\"https:\\\/\\\/softproof.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/SpectraProof_spotcolor_rendering.png\",\"contentUrl\":\"https:\\\/\\\/softproof.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/SpectraProof_spotcolor_rendering.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/softproof.com\\\/spotcolor-rendering\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/softproof.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spotcolor Rendering\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/softproof.com\\\/#website\",\"url\":\"https:\\\/\\\/softproof.com\\\/\",\"name\":\"Softproof.com\",\"description\":\"Softproofing made easy ...\",\"publisher\":{\"@id\":\"https:\\\/\\\/softproof.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/softproof.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/softproof.com\\\/#organization\",\"name\":\"Proof GmbH\",\"url\":\"https:\\\/\\\/softproof.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/softproof.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/softproof.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/spicon.png\",\"contentUrl\":\"https:\\\/\\\/softproof.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/spicon.png\",\"width\":250,\"height\":250,\"caption\":\"Proof GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/softproof.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Renderizado Spotcolor - Softproof.com","description":"SpectraProof le permite importar los datos espectrales medidos de cualquier archivo CxF o CGATS para mostrarlos en spotcolor .","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/softproof.com\/es\/renderizado-de-colores-planos\/","og_locale":"es_ES","og_type":"article","og_title":"Spotcolor Rendering - Softproof.com","og_description":"SpectraProof allows you to import measured spectral data from any CxF or CGATS files to display spotcolor .","og_url":"https:\/\/softproof.com\/es\/renderizado-de-colores-planos\/","og_site_name":"Softproof.com","article_modified_time":"2025-05-30T22:23:16+00:00","og_image":[{"width":407,"height":644,"url":"https:\/\/softproof.com\/wp-content\/uploads\/2023\/11\/SpectraProof_spotcolor_rendering.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/softproof.com\/spotcolor-rendering\/","url":"https:\/\/softproof.com\/spotcolor-rendering\/","name":"Renderizado Spotcolor - Softproof.com","isPartOf":{"@id":"https:\/\/softproof.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/softproof.com\/spotcolor-rendering\/#primaryimage"},"image":{"@id":"https:\/\/softproof.com\/spotcolor-rendering\/#primaryimage"},"thumbnailUrl":"https:\/\/softproof.com\/wp-content\/uploads\/2023\/11\/SpectraProof_spotcolor_rendering.png","datePublished":"2023-10-25T08:04:03+00:00","dateModified":"2025-05-30T22:23:16+00:00","description":"SpectraProof le permite importar los datos espectrales medidos de cualquier archivo CxF o CGATS para mostrarlos en spotcolor .","breadcrumb":{"@id":"https:\/\/softproof.com\/spotcolor-rendering\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/softproof.com\/spotcolor-rendering\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/softproof.com\/spotcolor-rendering\/#primaryimage","url":"https:\/\/softproof.com\/wp-content\/uploads\/2023\/11\/SpectraProof_spotcolor_rendering.png","contentUrl":"https:\/\/softproof.com\/wp-content\/uploads\/2023\/11\/SpectraProof_spotcolor_rendering.png"},{"@type":"BreadcrumbList","@id":"https:\/\/softproof.com\/spotcolor-rendering\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/softproof.com\/"},{"@type":"ListItem","position":2,"name":"Spotcolor Rendering"}]},{"@type":"WebSite","@id":"https:\/\/softproof.com\/#website","url":"https:\/\/softproof.com\/","name":"Softproof.com","description":"Softproofing hecho f\u00e1cil ...","publisher":{"@id":"https:\/\/softproof.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/softproof.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/softproof.com\/#organization","name":"Proof GmbH","url":"https:\/\/softproof.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/softproof.com\/#\/schema\/logo\/image\/","url":"https:\/\/softproof.com\/wp-content\/uploads\/2023\/11\/spicon.png","contentUrl":"https:\/\/softproof.com\/wp-content\/uploads\/2023\/11\/spicon.png","width":250,"height":250,"caption":"Proof GmbH"},"image":{"@id":"https:\/\/softproof.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/softproof.com\/es\/wp-json\/wp\/v2\/pages\/1726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/softproof.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/softproof.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/softproof.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/softproof.com\/es\/wp-json\/wp\/v2\/comments?post=1726"}],"version-history":[{"count":9,"href":"https:\/\/softproof.com\/es\/wp-json\/wp\/v2\/pages\/1726\/revisions"}],"predecessor-version":[{"id":3380,"href":"https:\/\/softproof.com\/es\/wp-json\/wp\/v2\/pages\/1726\/revisions\/3380"}],"wp:attachment":[{"href":"https:\/\/softproof.com\/es\/wp-json\/wp\/v2\/media?parent=1726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}